{"id":10211,"date":"2022-02-24T20:25:26","date_gmt":"2022-02-24T20:25:26","guid":{"rendered":"https:\/\/nnpc.tempurl.host\/circulaire-sancties-rusland\/"},"modified":"2025-06-29T17:30:42","modified_gmt":"2025-06-29T17:30:42","slug":"rundbrief-zu-sanktionen-gegen-russland","status":"publish","type":"post","link":"https:\/\/nnpc-marine.com\/de\/rundbrief-zu-sanktionen-gegen-russland\/","title":{"rendered":"Rundbrief zu Sanktionen gegen Russland"},"content":{"rendered":"<p><strong>Die Lage in der Ukraine \u00e4ndert sich schnell. Zus\u00e4tzlich zu dem bereits angek\u00fcndigten Sanktionspaket werden in K\u00fcrze neue Sanktionen folgen, die sich st\u00e4rker auf die russische Wirtschaft und die Finanzinstitute auswirken werden. Dies d\u00fcrfte sich auch auf den Transport und den Zugang zu russischen H\u00e4fen auswirken.<\/strong><\/p>\n<p>Im Folgenden werden die neuen Sanktionen, die in den letzten Tagen angek\u00fcndigt wurden, kurz erl\u00e4utert.<\/p>\n<p><strong>Vereinigte Staaten:<\/strong><\/p>\n<p>Am 21. Februar unterzeichnete Pr\u00e4sident Biden ein neues Dekret gegen die Volksrepubliken Donezk und Luhansk in der Ukraine. Dieses Dekret verbietet:<\/p>\n<p>a. neue Investitionen in diesen Gebieten;<br \/>\nb. die Einfuhr von Waren, Dienstleistungen und Technologie aus diesen Gebieten in die USA; und<br \/>\nc. die Ausfuhr von Waren, Dienstleistungen oder Technologie aus den USA oder durch US-Personen in diese Gebiete.<\/p>\n<p>Am 22. Februar haben die USA Sanktionen gegen den russischen Finanzsektor verh\u00e4ngt. Infolgedessen wurden die Vnesheconombank (&#8222;VEB&#8220;) und die Promsvyazbank Public Joint Stock Company (&#8222;PSB&#8220;) und ihre Tochtergesellschaften in die SDN-Liste aufgenommen.<\/p>\n<p><strong>Vereinigtes K\u00f6nigreich<\/strong><\/p>\n<p>Die Sanktionen des Vereinigten K\u00f6nigreichs beschr\u00e4nken sich auf die Aufnahme von 5 russischen Banken (IS Bank, Rossiya Bank, PJSC Promsvyazbank, JSC Genbank und JSC Black Sea Bank Development and Reconstruction) und 3 Einzelpersonen in die UK-Sanktionslisten. Die britische Regierung hat au\u00dferdem angek\u00fcndigt, dass die bereits gegen die Krim verh\u00e4ngten Sanktionen auf die abtr\u00fcnnigen Republiken Donezk und Luhansk ausgedehnt werden sollen.<\/p>\n<p><strong>EU-Sanktionen<\/strong><\/p>\n<p>Am 22. Februar haben die EU-Mitgliedstaaten ihre politische Zustimmung zu einem neuen Sanktionspaket gegen Russland gegeben, das nun formell umgesetzt wird. Die Sanktionen richten sich gegen Einzelpersonen, Unternehmen und Banken. Der Handel zwischen der EU und den beiden abtr\u00fcnnigen Regionen wird untersagt. Die russischen Beh\u00f6rden werden auch von den europ\u00e4ischen Finanzm\u00e4rkten abgeschnitten sein.<\/p>\n<p>Da sich die Entwicklungen in einem rasanten Tempo vollziehen, handelt es sich hier um eine vorl\u00e4ufige Zusammenfassung. Heute wurden bereits weitere Ma\u00dfnahmen angek\u00fcndigt, die wir im Detail ver\u00f6ffentlichen werden. Wir beobachten die Situation weiterhin genau und werden weitere Updates ver\u00f6ffentlichen, sobald neue Entwicklungen eintreten. Wir raten unseren Mitgliedern, bei allen Reisen nach Russland Sanktionspr\u00fcfungen durchzuf\u00fchren, die Hoheitsgew\u00e4sser der Ukraine und Russlands im Schwarzen Meer bis auf weiteres zu meiden und sich bei Fragen per E-Mail an <a href=\"mailto:claims@nnpc-marine.com\">claims@nnpc-marine.com<\/a> an den NNPC zu wenden.<\/p>\n<p>Schlie\u00dflich empfehlen wir den Mitgliedern, die BIMCO-Sanktionsklausel f\u00fcr Zeitchartervertr\u00e4ge 2020 oder die BIMCO-Sanktionsklausel f\u00fcr Reisechartervertr\u00e4ge 2020 in ihre Befrachtungsvertr\u00e4ge aufzunehmen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Lage in der Ukraine \u00e4ndert sich schnell. Zus\u00e4tzlich zu dem bereits angek\u00fcndigten Sanktionspaket werden in K\u00fcrze neue Sanktionen folgen, die sich st\u00e4rker auf die russische Wirtschaft und die Finanzinstitute auswirken werden. Dies d\u00fcrfte sich auch auf den Transport und den Zugang zu russischen H\u00e4fen auswirken. Im Folgenden werden die neuen Sanktionen, die in den&#8230;<\/p>\n","protected":false},"author":4,"featured_media":16821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[15],"class_list":["post-10211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht","tag-russland"],"_links":{"self":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/10211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/comments?post=10211"}],"version-history":[{"count":0,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/10211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media\/16821"}],"wp:attachment":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media?parent=10211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/categories?post=10211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/tags?post=10211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}