{"id":13175,"date":"2024-04-10T07:00:02","date_gmt":"2024-04-10T07:00:02","guid":{"rendered":"https:\/\/nnpc.tempurl.host\/?p=13175"},"modified":"2025-06-29T17:28:42","modified_gmt":"2025-06-29T17:28:42","slug":"interview-mit-kapitaensreeder-jan-wind-ueber-die-romantik-der-seefahrt","status":"publish","type":"post","link":"https:\/\/nnpc-marine.com\/de\/interview-mit-kapitaensreeder-jan-wind-ueber-die-romantik-der-seefahrt\/","title":{"rendered":"Interview mit Kapit\u00e4nsreeder Jan Wind \u00fcber die Romantik der Seefahrt"},"content":{"rendered":"<section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1200\" height=\"750\" src=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2024\/04\/jan-wind-nnpc.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2024\/04\/jan-wind-nnpc.jpg 1200w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2024\/04\/jan-wind-nnpc-300x188.jpg 300w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2024\/04\/jan-wind-nnpc-1024x640.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column us_custom_e0937adc\"><div class=\"wpb_wrapper\"><p>\u201eDie sch\u00f6nste Reise zu machen, nicht nur die lukrativste, war immer die Devise.\u201c Wir interviewen Jan Wind, einen leidenschaftlichen maritimen Unternehmer, der als Kapit\u00e4nsreeder auf den Weltmeeren unterwegs war und ein florierendes Gesch\u00e4ft mit (Schiffs-)Kabeln aufgebaut hat. Nach seinem Ausscheiden als Gesch\u00e4ftsf\u00fchrer von Wind im Jahr 2022 konzentriert er sich jetzt ganz auf sein anderes Unternehmen, Amazon Shipping.<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Jan Wind verdient seinen Lebensunterhalt in der Schifffahrt, so beschreibt er sich selbst. Seine Vorfahren, die alle Jan hie\u00dfen, waren alle Seeleute, und so wuchs er in der N\u00e4he von Alkmaar auch mit dem sehnlichen Wunsch auf, die Weltmeere zu bereisen. Die Binnengew\u00e4sser Europas waren ihm zu klein, und so kaufte er mit achtundzwanzig Jahren sein erstes Schiff, die Lida, und begab sich in ein Abenteuer, das ihn bis heute nicht losgelassen hat. Und das immer mit der Unterst\u00fctzung und dem Rat des NNPC.<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:40px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Sie stammen also aus einer echten Seefahrerfamilie?<\/h2>\n<p>\u201eIn der Familie kursiert die Geschichte, dass einer meiner Vorfahren der erste in den Niederlanden war, der von einem Holz- auf ein Stahlschiff umgestiegen ist. \u201eEin Schiff aus Stahl kann doch nicht schwimmen, oder?\u201c, warnten ihn seine Dorfgenossen. Diese Abenteuerlust haben wir seit sechs Generationen im Blut. Ich bin in die Fu\u00dfstapfen meines Vaters getreten, der die Seefahrt der Binnenschifffahrt vorzog und sp\u00e4ter zu einem der Gesch\u00e4ftsf\u00fchrer der Reederei Wagenborg aufstieg. Eigentlich wollte er ein eigenes Frachtschiff haben, aber er heiratete jung und damit war diese Chance dahin. Nach meiner Ausbildung und einer Zeit als angestellter Steuermann habe ich das dann geschafft. Wenn man sein eigenes Schiff kauft, muss man sich in es verlieben. Die Lida war ein altes, aber gut seet\u00fcchtiges Schiff. Nach einer Renovierungsphase konnte ich damit weltweit fahren. Diese Freiheit hatte etwas Romantisches an sich.\u201c<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Wie haben Sie das maritime Unternehmertum in Angriff genommen?<\/h2>\n<p>\u201eIn den Anf\u00e4ngen, um 1990 herum, habe ich immer wieder geschaut, welche Frachten ich \u00fcbernehmen und an sch\u00f6ne Orte bringen k\u00f6nnte. Da ich fr\u00fch in ein Satellitenkommunikationssystem investiert habe, wurde das Befrachten immer erfolgreicher. Mit dem Netzwerk, das ich aufgebaut habe, habe ich st\u00e4ndig Frachten bekommen und bin um die ganze Welt gefahren. Die sch\u00f6nste Reise zu machen, nicht nur die lukrativste, war immer die Devise. Zum Gl\u00fcck ging das sehr oft Hand in Hand.\u201c<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Ihr Unternehmen Wind, dessen Gesch\u00e4ftsf\u00fchrer Sie bis 2022 waren, hat sich schlie\u00dflich auf den Transport von Kabeln spezialisiert. Wie sind Sie zu dieser Spezialisierung gekommen?<\/h2>\n<p>\u201eDas hat sich einfach so ergeben, weil man mir diese Fracht angeboten hat. Dann habe ich auf dem Schiff gro\u00dfe Trommeln eingebaut, auf die sie aufgerollt werden konnten. Das war ein aussichtsreiches Gesch\u00e4ft. Au\u00dferdem waren es gute Ladungen: langes Laden, langes L\u00f6schen und dann in alle Regionen der Welt, wo diese Kabel verlegt wurden. Letzteres wird von gro\u00dfen Spezialschiffen \u00fcbernommen, die viel zu teuer sind, um das Material selbst abzuholen. Und da war ich dann zur Stelle.\u201c<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Mit Erfolg. Sie haben sich von einem kleinen Unternehmen zu einem globalen Dienstleister f\u00fcr Seekabel entwickelt, mit Niederlassungen in Alkmaar, den USA und Taiwan. Wie haben Sie das geschafft?<\/h2>\n<p>\u201eDie Lida hat sich in der Schifffahrt einen Namen als gutes Schiff f\u00fcr Kabel gemacht. Dann habe ich zwei weitere Schwesterschiffe gekauft, um noch mehr transportieren zu k\u00f6nnen. Alte Schiffe, die wir \u00fcberholt haben. Ich kaufte auch einen Dreitausendtonner, die Suzie Q, nach einem Song von Creedence Clearwater Revival. Irgendwann wurde es mir zu viel, das alles vom Schiff aus zu managen und ich musste an Land in ein B\u00fcro in Alkmaar gehen. Ich habe dann weitere Leute dazugeholt, und nach und nach haben wir das Ganze ausgebaut.\u201c<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Welche Rolle hat der NNPC bei all dem gespielt?<\/h2>\n<p>\u201eDie Lida war von Anfang an beim NNPC versichert. Ich lernte die Leute dort kennen und verstand mich gut mit ihnen. Jetzt lautet meine erste Regel: Versuche, Sch\u00e4den zu vermeiden. Die zweite Regel lautet: Wenn es einen Schaden gibt, kl\u00e4re ihn so schnell wie m\u00f6glich vor Ort mit dem Betroffenen. Das konnte ich oft problemlos per Handschlag erledigen. Trotzdem brauchte ich den NNPC manchmal als Berater. Ich hatte zum Beispiel einmal einen Streit mit einer lokalen Charterfirma, die auch Mitglied des NNPC war. Der wurde durch eure Vermittlung erfolgreich beigelegt. Auch als wir ins Kabelgesch\u00e4ft eingestiegen sind, hat mir der NNPC sehr geholfen. Ich habe als kleiner Betrieb angefangen, mit nur einem Schiff. In Anbetracht des enormen Werts dieser Kabel kam ich damals als Frachtf\u00fchrer manchmal gar nicht erst in Frage Gemeinsam mit dem NNPC habe ich deshalb eine tolle Brosch\u00fcre f\u00fcr unser Schiff zusammengestellt mit Informationen dar\u00fcber, wie eventuelle Sch\u00e4den an den Kabeln erstattet werden, alles durchkalkuliert und mit einem Begleitschreiben&#8230; Damit hat mir der NNPC sehr geholfen.<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Der Ruf nach Nachhaltigkeit in der Schifffahrt wird immer lauter. Wie gehen Sie damit um?<\/h2>\n<p>\u201eDamals habe ich sorgf\u00e4ltig gepr\u00fcft, ob wir die Lida, die urspr\u00fcnglich einen Dieselmotor hat, unter Segel setzen k\u00f6nnen. Ehrlich gesagt, tat ich das auch aus romantischen Erw\u00e4gungen. Urspr\u00fcnglich hatten wir einen Entwurf mit einem einzigen Hilfssegel, aber daraus wurden dann sogar 10 Segel! Aus diesen Pl\u00e4nen ist leider nichts geworden. Wir haben jedoch, auch aus kommerziellen Gr\u00fcnden, eines unserer Schiffe umgebaut, um alte Koaxialkabel vom Meeresboden zu heben. Auf diese Weise haben wir den Meeresboden betr\u00e4chtlich ges\u00e4ubert.\u201c<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Inzwischen sind Sie und Ihre Familie schon seit einiger Zeit wieder auf dem Festland. Lockt das Leben eines Kapit\u00e4ns noch immer?<\/h2>\n<p>\u201eIch w\u00fcrde gerne wieder einmal eine Reise machen, habe aber akzeptiert, dass ich nicht mehr als Kapit\u00e4n t\u00e4tig bin. Ich habe auch als Unternehmer sehr viel zu tun. Aber ich bin immer noch regelm\u00e4\u00dfig auf einer Jacht unterwegs! Dort finde ich wieder diesen Hauch von Romantik.\u201c<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>M\u00f6chten Sie den Lesern abschlie\u00dfend noch etwas mit auf den Weg geben?<\/h2>\n<p>\u201eIch beobachte, dass der Kreis der Kapit\u00e4nsreeder immer kleiner wird. Niemand traut sich mehr, diesen Schritt zu wagen. Ich denke, das liegt an der Vorstellung, dass man es als Kleinunternehmer heutzutage nicht mehr schaffen kann, dass nur gro\u00dfe Unternehmen profitabel sein k\u00f6nnen. Dem muss ich entschieden widersprechen. Es gab und gibt, genau wie vor 34 Jahren, noch immer Platz f\u00fcr Kapit\u00e4nsreeder, vorausgesetzt, man ist mit Leib und Seele bei der Sache. Enthusiasmus, Professionalit\u00e4t, guter Service: Auf eigene Faust kann man besser und effizienter arbeiten und mehr Gewinn machen. Und die Romantik gibt es immer noch. Auch wenn die Vorschriften ein wenig strenger sind als fr\u00fcher. Die Freiheit, die Reisen, die M\u00f6glichkeiten&#8230; Die besten Frachten in die sch\u00f6nsten Gegenden bringen. Damit l\u00e4sst sich immer noch Geld verdienen, lassen Sie sich nicht einreden, dass das nicht m\u00f6glich ist!\u201c<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1200\" height=\"485\" src=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2023\/12\/nnpc-kantoor-1200.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2023\/12\/nnpc-kantoor-1200.jpg 1200w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2023\/12\/nnpc-kantoor-1200-300x121.jpg 300w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2023\/12\/nnpc-kantoor-1200-1024x414.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_d36be09e\"><div class=\"wpb_wrapper\"><h2>Kontakt<\/h2>\n<p>M\u00f6chten Sie sich wie Jan Wind auf das Abenteuer als Kapit\u00e4nsreeder einlassen oder befinden Sie sich gerade in der Existenzgr\u00fcndung als maritimer Unternehmer? Der NNPC steht Ihnen mit Rat und Tat zur Seite! <a href=\"https:\/\/nnpc-marine.com\/de\/kontakt\/\">Nehmen Sie hier gleich Kontakt mit uns auf.<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"\u201eDie sch\u00f6nste Reise zu machen, nicht nur die lukrativste, war immer die Devise.\u201c Wir interviewen Jan Wind, einen leidenschaftlichen maritimen Unternehmer, der als Kapit\u00e4nsreeder auf den Weltmeeren unterwegs war und ein florierendes Gesch\u00e4ft mit (Schiffs-)Kabeln aufgebaut hat. Nach seinem Ausscheiden als Gesch\u00e4ftsf\u00fchrer von Wind im Jahr 2022 konzentriert er sich jetzt ganz auf sein anderes...","protected":false},"author":4,"featured_media":13375,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[61],"tags":[],"class_list":["post-13175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interview-de"],"_links":{"self":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/13175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/comments?post=13175"}],"version-history":[{"count":0,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/13175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media\/13375"}],"wp:attachment":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media?parent=13175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/categories?post=13175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/tags?post=13175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}