{"id":13188,"date":"2024-04-11T10:05:16","date_gmt":"2024-04-11T10:05:16","guid":{"rendered":"https:\/\/nnpc.tempurl.host\/13e-sanctiepakket-van-de-eu-tegen-rusland-update\/"},"modified":"2025-06-29T17:28:42","modified_gmt":"2025-06-29T17:28:42","slug":"13-sanktionspaket-der-eu-gegen-russland-update","status":"publish","type":"post","link":"https:\/\/nnpc-marine.com\/de\/13-sanktionspaket-der-eu-gegen-russland-update\/","title":{"rendered":"13. Sanktionspaket der EU gegen Russland: Update"},"content":{"rendered":"<p><em>Wir verweisen auf unsere <a href=\"https:\/\/nnpc.tempurl.host\/russland-ukraine-konflikt-updates\/?lang=de\">fr\u00fcheren Rundschreiben<\/a> zu den Sanktionen gegen Russland als Reaktion auf den Konflikt in der Ukraine, die auf der Website des NNPC zu finden sind.<\/em><\/p>\n<p><strong>K\u00fcrzlich wurde ein Schiff, das eine Fracht von St. Petersburg in die USA transportierte, von deutschen Beh\u00f6rden im Hafen von Rostock festgehalten. Das Schiff hatte auf dem Weg einen Umweg nach Rostock gemacht, um Reparaturen durchzuf\u00fchren und wurde anschlie\u00dfend festgehalten, weil die Fracht Sanktionen unterliegen w\u00fcrde.<\/strong><\/p>\n<p>Obwohl die Eigner Widerspruch eingelegt haben, macht dieser Vorfall deutlich, wie wichtig es ist, sorgf\u00e4ltig zu pr\u00fcfen, dass der Transport der Fracht nicht sanktioniert wurde und dass die an der Verschiffung beteiligten Parteien nicht auf einer Sanktionsliste stehen.<\/p>\n<p>Wir verweisen unsere Mitglieder auf das j\u00fcngste (13.) Sanktionspaket, das die EU-Kommission am 23. Februar 2024 ver\u00f6ffentlicht hat und das eine Reihe neuer Ma\u00dfnahmen, insbesondere im Bereich der Drohnen, vorsieht und sich auch gegen andere Unternehmen und Personen im Zusammenhang mit dem Konflikt in der Ukraine richtet.<\/p>\n<p>Die wichtigsten Punkte des 13. Sanktionspakets lauten wie folgt:<\/p>\n<ul>\n<li><strong>Erweiterung der sanktionierten Parteien:<\/strong> Die Sanktionsliste wurde um insgesamt 194 Personen, darunter 106 Einzelpersonen und 88 Unternehmen, erweitert. Das Paket zielt insbesondere auf den russischen milit\u00e4risch-industriellen Komplex ab, einschlie\u00dflich Unternehmen, die an der Herstellung von Raketen, Drohnen, Milit\u00e4rfahrzeugen und anderen Waffen beteiligt sind. F\u00fcr die vollst\u00e4ndige Liste der sanktionierten Personen und Unternehmen, <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/PDF\/?uri=OJ:L_202400746\" target=\"_blank\" rel=\"noopener\">klicken Sie bitte hier<\/a>.<\/li>\n<li><strong>Handelsma\u00dfnahmen:<\/strong> Mit dem Paket werden Ma\u00dfnahmen eingef\u00fchrt, die Russlands Erwerb westlicher Technologien, die f\u00fcr seine milit\u00e4rischen Operationen von entscheidender Bedeutung sind, insbesondere im Bereich der Drohnenkriegsf\u00fchrung, behindern sollen. Gegen 27 russische Unternehmen und Unternehmen aus Drittl\u00e4ndern, die mit dem russischen milit\u00e4risch-industriellen Komplex verbunden sind, wurden Ausfuhrbeschr\u00e4nkungen verh\u00e4ngt. Damit wird die Liste der kritischen Technologien f\u00fcr das russische Milit\u00e4r erweitert, darunter auch Komponenten, die bei der Entwicklung von Drohnen verwendet werden, wie elektrische Transformatoren, statische Umformer, Induktoren und Aluminiumkondensatoren.<\/li>\n<\/ul>\n<p>Da die Sanktionsliste mit jedem neuen Paket l\u00e4nger wird, raten wir unseren Mitgliedern, ihre Gesch\u00e4fts- und Vertragspartner regelm\u00e4\u00dfig auf Sanktionen zu \u00fcberpr\u00fcfen, um Risiken zu minimieren.<\/p>\n<p>Ausf\u00fchrlichere Informationen \u00fcber das neueste Sanktionspaket finden Sie hier auf der <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/en\/ip_24_963\" target=\"_blank\" rel=\"noopener\">offiziellen Website der Europ\u00e4ischen Kommission<\/a>.<\/p>\n<p>Bei Fragen zu EU-Sanktionen oder \u00e4hnlichen Angelegenheiten k\u00f6nnen sich unsere Mitglieder an das NNPC-Schadenteam unter <a href=\"mailto:claims@nnpc-marine.com\">claims@nnpc-marine.com<\/a> wenden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir verweisen auf unsere fr\u00fcheren Rundschreiben zu den Sanktionen gegen Russland als Reaktion auf den Konflikt in der Ukraine, die auf der Website des NNPC zu finden sind. K\u00fcrzlich wurde ein Schiff, das eine Fracht von St. Petersburg in die USA transportierte, von deutschen Beh\u00f6rden im Hafen von Rostock festgehalten. Das Schiff hatte auf dem&#8230;<\/p>\n","protected":false},"author":4,"featured_media":13180,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[15],"class_list":["post-13188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht","tag-russland"],"_links":{"self":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/13188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/comments?post=13188"}],"version-history":[{"count":0,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/13188\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media\/13180"}],"wp:attachment":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media?parent=13188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/categories?post=13188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/tags?post=13188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}