{"id":13854,"date":"2024-09-12T08:11:24","date_gmt":"2024-09-12T08:11:24","guid":{"rendered":"https:\/\/nnpc.tempurl.host\/?p=13854"},"modified":"2025-06-29T17:28:40","modified_gmt":"2025-06-29T17:28:40","slug":"neue-niederlaendische-binnenschifffahrtspolizeiverordnung-bpr-erlaubt-unbemannte-schiffe-ab-1-januar-2025","status":"publish","type":"post","link":"https:\/\/nnpc-marine.com\/de\/neue-niederlaendische-binnenschifffahrtspolizeiverordnung-bpr-erlaubt-unbemannte-schiffe-ab-1-januar-2025\/","title":{"rendered":"Neue niederl\u00e4ndische Binnenschifffahrtspolizeiverordnung (BPR) erlaubt unbemannte Schiffe ab 1. Januar 2025"},"content":{"rendered":"<p><strong>Ab dem 1. Januar 2025 ist es nach der niederl\u00e4ndischen Binnenschifffahrtspolizeiverordnung (BPR) nicht mehr erforderlich, dass Schiffe auf den niederl\u00e4ndischen Binnenwasserstra\u00dfen mit einer Besatzung an Bord fahren. Von diesem Zeitpunkt an k\u00f6nnen Betroffene eine Freistellung f\u00fcr autonomes oder ferngesteuertes Fahren beantragen.<\/strong><\/p>\n<p>Diese \u00c4nderung wurde k\u00fcrzlich vom niederl\u00e4ndischen Minister f\u00fcr Infrastruktur und Wasserwirtschaft angek\u00fcndigt. Das Ministerium unterst\u00fctzt seit 2017 die Entwicklung des autonomen Fahrens durch das Programm \u201eSmart Shipping\u201c, das Experimente mit innovativer \u201eintelligenter Schifffahrt\u201c auf nationalen Wasserstra\u00dfen f\u00f6rdert. Die ferngesteuerte und autonome Schifffahrt wird als Schl\u00fcsselkomponente f\u00fcr einen sichereren und nachhaltigeren Wasserstra\u00dfentransport angesehen, wobei die Automatisierung eine wesentliche Rolle bei der Erh\u00f6hung der Sicherheit, Nachhaltigkeit und Wettbewerbsf\u00e4higkeit der Schifffahrtsbranche spielt.<\/p>\n<p>Bislang musste jedes Schiff, das ferngesteuert oder autonom fuhr, eine menschliche Besatzung an Bord haben. In den letzten Jahren wurde jedoch die Entwicklung und Anwendung innovativer Techniken, die eine unbemannte Navigation erm\u00f6glichen, zunehmend gef\u00f6rdert. Ein rechtlicher Rahmen, der das autonome Fahren in Zukunft regeln soll, ist ebenfalls in Arbeit. In der Zwischenzeit kann bereits ab n\u00e4chstem Jahr \u00fcber die Website von Rijkswaterstaat, der obersten Stra\u00dfen- und Wasserbaubeh\u00f6rde der Niederlande, eine Freistellung daf\u00fcr beantragt werden.<\/p>\n<p>Gleichzeitig unternimmt die weltweite Seeschifffahrtsindustrie im Rahmen der Initiative \u201eMaritime Autonomous Sea Vessels\u201c (MASS) neue Vorst\u00f6\u00dfe, wie z. B. die Entwicklung von Mustervorschriften innerhalb der Internationalen Seeschifffahrtsorganisation (IMO). Die IMO strebt die Fertigstellung der MASS-Richtlinie, die auch f\u00fcr die Nordsee gelten wird, f\u00fcr das Jahr 2028 an. Weitere Informationen sind auf der Website der IMO zu finden.<\/p>\n<p>Diese \u00c4nderung ist ein wichtiger Schritt bei der Entwicklung eines gesetzlichen Rahmens f\u00fcr den Einsatz von autonomen Schiffen in den Niederlanden.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.rijkswaterstaat.nl\/water\/wetten-regels-en-vergunningen\/scheepvaart\/scheepvaartverkeerswet\/smart-shipping\" target=\"_blank\" rel=\"noopener\">https:\/\/www.rijkswaterstaat.nl\/water\/wetten-regels-en-vergunningen\/scheepvaart\/scheepvaartverkeerswet\/smart-shipping<\/a><\/li>\n<li><a href=\"https:\/\/www.imo.org\/en\/MediaCentre\/HotTopics\/Pages\/Autonomous-shipping.aspx\" target=\"_blank\" rel=\"noopener\">https:\/\/www.imo.org\/en\/MediaCentre\/HotTopics\/Pages\/Autonomous-shipping.aspx<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ab dem 1. Januar 2025 ist es nach der niederl\u00e4ndischen Binnenschifffahrtspolizeiverordnung (BPR) nicht mehr erforderlich, dass Schiffe auf den niederl\u00e4ndischen Binnenwasserstra\u00dfen mit einer Besatzung an Bord fahren. Von diesem Zeitpunkt an k\u00f6nnen Betroffene eine Freistellung f\u00fcr autonomes oder ferngesteuertes Fahren beantragen. Diese \u00c4nderung wurde k\u00fcrzlich vom niederl\u00e4ndischen Minister f\u00fcr Infrastruktur und Wasserwirtschaft angek\u00fcndigt. Das Ministerium&#8230;<\/p>\n","protected":false},"author":4,"featured_media":13850,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[],"class_list":["post-13854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht"],"_links":{"self":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/13854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/comments?post=13854"}],"version-history":[{"count":0,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/13854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media\/13850"}],"wp:attachment":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media?parent=13854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/categories?post=13854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/tags?post=13854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}