{"id":18039,"date":"2025-09-02T09:24:30","date_gmt":"2025-09-02T09:24:30","guid":{"rendered":"https:\/\/nnpc-marine.com\/?p=18039"},"modified":"2026-04-28T10:59:11","modified_gmt":"2026-04-28T10:59:11","slug":"neue-tuerkische-seeverkehrsvorschriften-in-bezug-auf-israel","status":"publish","type":"post","link":"https:\/\/nnpc-marine.com\/de\/neue-tuerkische-seeverkehrsvorschriften-in-bezug-auf-israel\/","title":{"rendered":"Neue t\u00fcrkische Seeverkehrsvorschriften in Bezug auf Israel"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_8c9a1c3b\"><div class=\"wpb_wrapper\"><p>Mit Wirkung vom 20. August 2025 haben die t\u00fcrkischen Beh\u00f6rden neue Ma\u00dfnahmen eingef\u00fchrt, die sich auf Schiffs- und Frachtaktivit\u00e4ten in Bezug auf Israel auswirken. Die neuen Ma\u00dfnahmen stellen eine erhebliche politische \u00c4nderung dar und werden direkte Auswirkungen auf Parteien haben, die Fracht von oder nach Israel transportieren.<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"w-image us_custom_7cd9500e align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1200\" height=\"670\" src=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/09\/New_Turkish_Maritime_Regulations-Affecting_Israel_Linked_Shipping_Operations.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/09\/New_Turkish_Maritime_Regulations-Affecting_Israel_Linked_Shipping_Operations.jpg 1200w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/09\/New_Turkish_Maritime_Regulations-Affecting_Israel_Linked_Shipping_Operations-300x168.jpg 300w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/09\/New_Turkish_Maritime_Regulations-Affecting_Israel_Linked_Shipping_Operations-1024x572.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Die wichtigsten Ma\u00dfnahmen sind wie folgt:<\/p>\n<ul>\n<li>Schiffe aus einem israelischen Hafen d\u00fcrfen keine t\u00fcrkischen H\u00e4fen anlaufen. Schiffe d\u00fcrfen auch nicht direkt von der T\u00fcrkei aus zu einem israelischen Hafen auslaufen.<\/li>\n<li>Die t\u00fcrkischen Beh\u00f6rden werden im Rahmen der Vorabfertigungsverfahren CSR- (Continuous Synopsis Record) und ISM-Daten (International Safety Management) sowie Informationen zum Schiffsmanagement anfordern. Schiffe, die operative Verbindungen zu Israel haben, kann der Zugang zu t\u00fcrkischen H\u00e4fen verweigert werden.<\/li>\n<li>S\u00e4mtliche Ladungen mit Bezug zu Israel d\u00fcrfen nicht in t\u00fcrkischen H\u00e4fen umgeschlagen werden.<\/li>\n<li>Israelbezogene Ladungen d\u00fcrfen jedoch im Transit bef\u00f6rdert werden, mit Ausnahme von Gefahrg\u00fctern der IMO-Klasse 1 (Explosivstoffe) und Klasse 7 (radioaktive Stoffe).<\/li>\n<\/ul>\n<p>Schiffe, die gegen diese Vorschriften versto\u00dfen, erhalten keine Einlaufgenehmigung f\u00fcr die T\u00fcrkei und es k\u00f6nnen Geldstrafen von bis zu 12.100 USD verh\u00e4ngt werden. Obwohl die Beh\u00f6rden noch keine offiziellen Richtlinien f\u00fcr die Einf\u00fchrung dieser Beschr\u00e4nkungen ver\u00f6ffentlicht haben, gehen wir davon aus, dass die Durchsetzung bereits begonnen hat. Wir beobachten die Situation aufmerksam und werden Sie auf dem Laufenden halten, sobald offizielle Informationen verf\u00fcgbar sind.<\/p>\n<p>Bei weiteren Fragen oder f\u00fcr weitere Informationen wenden Sie sich bitte an <a href=\"mailto:claims@nnpc-marine.com\">claims@nnpc-marine.com<\/a>.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Mit Wirkung vom 20. August 2025 haben die t\u00fcrkischen Beh\u00f6rden neue Ma\u00dfnahmen eingef\u00fchrt, die sich auf Schiffs- und Frachtaktivit\u00e4ten in Bezug auf Israel auswirken. Die neuen Ma\u00dfnahmen stellen eine erhebliche politische \u00c4nderung dar und werden direkte Auswirkungen auf Parteien haben, die Fracht von oder nach Israel transportieren. Die wichtigsten Ma\u00dfnahmen sind wie folgt: Schiffe aus...","protected":false},"author":9,"featured_media":18030,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[174,110,114,223],"class_list":["post-18039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht","tag-cargo-de-2","tag-israel-de","tag-ladung","tag-turkey"],"_links":{"self":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/18039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/comments?post=18039"}],"version-history":[{"count":0,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/18039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media\/18030"}],"wp:attachment":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media?parent=18039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/categories?post=18039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/tags?post=18039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}