{"id":18132,"date":"2025-09-29T13:10:56","date_gmt":"2025-09-29T13:10:56","guid":{"rendered":"https:\/\/nnpc-marine.com\/sailing-to-the-united-states-what-certificates-are-necessary\/"},"modified":"2026-04-28T10:03:06","modified_gmt":"2026-04-28T10:03:06","slug":"fahrt-in-die-vereinigten-staaten-welche-zertifikate-benoetigen-sie","status":"publish","type":"post","link":"https:\/\/nnpc-marine.com\/de\/fahrt-in-die-vereinigten-staaten-welche-zertifikate-benoetigen-sie\/","title":{"rendered":"Fahrt in die Vereinigten Staaten: Welche Zertifikate ben\u00f6tigen Sie?"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_8c9a1c3b\"><div class=\"wpb_wrapper\"><p>Als NNPC Marine Insurance erhalten wir zunehmend Anfragen von Mitgliedern zu den zus\u00e4tzlichen Zertifikaten, die f\u00fcr Fahrten in die Vereinigten Staaten (USA) erforderlich sind. Wir stellen fest, dass es hier gelegentlich Unklarheiten gibt, weshalb wir die wichtigsten Zertifikate und Bonds im Folgenden nochmals erl\u00e4utern m\u00f6chten.<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"w-image us_custom_7cd9500e align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1200\" height=\"670\" src=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/09\/sailing_united_states_certificates_necessary.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/09\/sailing_united_states_certificates_necessary.jpg 1200w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/09\/sailing_united_states_certificates_necessary-300x168.jpg 300w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/09\/sailing_united_states_certificates_necessary-1024x572.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>1. Certificate of Financial Responsibility (COFR) und COFR-Garanty<\/h2>\n<p>Das COFR gilt als Nachweis, dass ein Schiff \u00fcber ausreichenden Versicherungsschutz verf\u00fcgt, um etwaige Sch\u00e4den infolge einer \u00d6lverschmutzung oder sonstiger Gew\u00e4sserverunreinigungen abdecken zu k\u00f6nnen. Das COFR wird von der U.S. Coast Guard (USCG) ausgestellt, jedoch ausschlie\u00dflich dann, wenn zuvor eine entsprechende COFR-Garanty vorgelegt wurde.<\/p>\n<ul>\n<li>Ein COFR ist verpflichtend f\u00fcr:<\/li>\n<li>Schiffe mit mehr als 100 BRZ (GT) und\/oder Schiffe, die \u00d6l innerhalb der amerikanischen Ausschlie\u00dflichen Wirtschaftszone (EEZ) transportieren.<\/li>\n<\/ul>\n<p>Obwohl das COFR grunds\u00e4tzlich eine G\u00fcltigkeitsdauer von drei Jahren aufweist, muss die dazugeh\u00f6rige Garantie j\u00e4hrlich erneuert werden.<\/p>\n<p>Um Verz\u00f6gerungen zu vermeiden, empfehlen wir, den Antragsprozess mindestens 30 Tage vor der Ankunft in den USA zu starten.<\/p>\n<h2>2. Kalifornisches COFR<\/h2>\n<p>Der Bundesstaat Kalifornien verfolgt strengere Umweltvorschriften als die US-Bundesregierung. Daher ist f\u00fcr das Anlaufen eines Hafens in Kalifornien zus\u00e4tzlich ein separates, staatliches COFR erforderlich.<\/p>\n<p>Dieses sogenannte California COFR muss sp\u00e4testens 10 Tage vor Einlaufen in einen kalifornischen Hafen beantragt werden. Bitte beachten Sie, dass dieses Zertifikat eine G\u00fcltigkeit von zwei Jahren besitzt \u2013 im Gegensatz zu der auf Bundesebene geltenden Laufzeit von drei Jahren.<\/p>\n<h2>3. International Carrier Bond (ICB)<\/h2>\n<p>Der International Carrier Bond (ICB) dient als Sicherheitsleistung gegen\u00fcber dem U.S. Customs and Border Protection (CBP). Er stellt sicher, dass etwaige Bu\u00dfgelder, Steuern oder andere Abgaben, die im Zusammenhang mit dem Anlaufen eines US-amerikanischen Hafens entstehen, ordnungsgem\u00e4\u00df entrichtet werden.<\/p>\n<p>Ein ICB ist zwingend erforderlich, bevor ein Schiff in einem US-Hafen geladen oder entladen wird.<\/p>\n<p>Der Bond kann in zwei Varianten abgeschlossen werden:<\/p>\n<ul>\n<li>Single Entry Bond (f\u00fcr einen einmaligen Hafenanlauf), oder<\/li>\n<li>Continuous Bond (f\u00fcr die Dauer eines Kalenderjahres).<\/li>\n<\/ul>\n<p>Ein wichtiger Hinweis: Ein Jahresbond (Continuous Bond) kostet in der Regel <strong>nicht mehr<\/strong> als ein Bond f\u00fcr den einmaligen Zugang.<\/p>\n<p>Auch bei der H\u00f6he der B\u00fcrgschaftssumme bestehen Unterschiede:<\/p>\n<ul>\n<li>In der Regel gen\u00fcgt eine Summe von 100.000 USD,<\/li>\n<li>F\u00fcr das Anlaufen des Hafens von Miami ist jedoch eine erh\u00f6hte Mindestdeckung von 150.000 USD vorgeschrieben.<\/li>\n<\/ul>\n<p>Selbstverst\u00e4ndlich k\u00f6nnen Sie die erforderlichen COFRs, Garantien sowie die notwendigen Bonds eigenst\u00e4ndig beantragen.<\/p>\n<p>Gerne stehen wir Ihnen jedoch unterst\u00fctzend zur Seite \u2013 insbesondere in Zusammenarbeit mit unseren bew\u00e4hrten Partnern SIGCO und Shoreline. F\u00fcr R\u00fcckfragen oder individuelle Unterst\u00fctzung wenden Sie sich bitte an unser Underwriting-Team unter: <a href=\"mailto:underwriting@nnpc-marine.com\">underwriting@nnpc-marine.com<\/a>.<\/p>\n<p><em>Hinweis: <\/em><em>Dieser Artikel bezieht sich ausschlie\u00dflich auf die zus\u00e4tzlichen Zertifikate f\u00fcr Fahrten in die USA \u2013 nicht auf weitere betriebliche Anforderungen wie z.\u202fB. das Vorhandensein eines Response Plans oder die Mitgliedschaft bei einer Oil Spill Response Organization (OSRO).<\/em><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Als NNPC Marine Insurance erhalten wir zunehmend Anfragen von Mitgliedern zu den zus\u00e4tzlichen Zertifikaten, die f\u00fcr Fahrten in die Vereinigten Staaten (USA) erforderlich sind. Wir stellen fest, dass es hier gelegentlich Unklarheiten gibt, weshalb wir die wichtigsten Zertifikate und Bonds im Folgenden nochmals erl\u00e4utern m\u00f6chten. 1. Certificate of Financial Responsibility (COFR) und COFR-Garanty Das COFR...","protected":false},"author":4,"featured_media":18127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[106,84],"class_list":["post-18132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht","tag-underwriting-de","tag-usa-de"],"_links":{"self":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/18132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/comments?post=18132"}],"version-history":[{"count":0,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/18132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media\/18127"}],"wp:attachment":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media?parent=18132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/categories?post=18132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/tags?post=18132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}