{"id":18678,"date":"2025-11-17T13:09:15","date_gmt":"2025-11-17T13:09:15","guid":{"rendered":"https:\/\/nnpc-marine.com\/update-suspension-of-u-s-and-chinese-port-charges-announced\/"},"modified":"2026-04-28T09:53:44","modified_gmt":"2026-04-28T09:53:44","slug":"update-aussetzung-der-amerikanischen-und-chinesischen-hafengebuehren-angekuendigt","status":"publish","type":"post","link":"https:\/\/nnpc-marine.com\/de\/update-aussetzung-der-amerikanischen-und-chinesischen-hafengebuehren-angekuendigt\/","title":{"rendered":"Update: Aussetzung der amerikanischen und chinesischen Hafengeb\u00fchren angek\u00fcndigt"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_8c9a1c3b\"><div class=\"wpb_wrapper\"><p>Die Vereinigten Staaten und China haben vereinbart, ihre gegenseitigen Hafengeb\u00fchren f\u00fcr Schiffe mit Wirkung vom 10. November 2025 f\u00fcr ein Jahr auszusetzen. Dies ist das Ergebnis von Handelsgespr\u00e4chen Ende Oktober 2025.<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"w-image us_custom_7cd9500e align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1200\" height=\"670\" src=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/11\/suspension_us_chinese_port_charges_announced.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/11\/suspension_us_chinese_port_charges_announced.jpg 1200w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/11\/suspension_us_chinese_port_charges_announced-300x168.jpg 300w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2025\/11\/suspension_us_chinese_port_charges_announced-1024x572.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Die USA werden die Ma\u00dfnahmen gegen Chinas Seeverkehrs-, Logistik- und Schiffbausektoren vor\u00fcbergehend aussetzen. Gleichzeitig setzen die USA die Verhandlungen mit China fort und arbeiten mit S\u00fcdkorea und Japan zusammen, um den amerikanischen Schiffbausektor zu st\u00e4rken. China hat best\u00e4tigt, dass es im Gegenzug die Gegenma\u00dfnahmen gegen amerikanische Schiffe aussetzen wird. Es ist noch unklar, ob ein Erstattungs- oder Ausgleichsmechanismus f\u00fcr Abgaben eingerichtet wird, die zwischen dem 14. Oktober und dem 10. November 2025 bereits erhoben wurden.<\/p>\n<p>Der NNPC beobachtet die Situation aufmerksam und wird seine Mitglieder informieren, sobald neue Informationen verf\u00fcgbar sind. Wenn Sie Fragen haben, wenden Sie sich bitte per E-Mail an c<a href=\"mailto:laims@nnpc-marine.com\">laims@nnpc-marine.com<\/a> an das NNPC-Schadenteam.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Die Vereinigten Staaten und China haben vereinbart, ihre gegenseitigen Hafengeb\u00fchren f\u00fcr Schiffe mit Wirkung vom 10. November 2025 f\u00fcr ein Jahr auszusetzen. Dies ist das Ergebnis von Handelsgespr\u00e4chen Ende Oktober 2025. Die USA werden die Ma\u00dfnahmen gegen Chinas Seeverkehrs-, Logistik- und Schiffbausektoren vor\u00fcbergehend aussetzen. Gleichzeitig setzen die USA die Verhandlungen mit China fort und arbeiten...","protected":false},"author":7,"featured_media":18672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[111,84],"class_list":["post-18678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht","tag-china-de","tag-usa-de"],"_links":{"self":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/18678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/comments?post=18678"}],"version-history":[{"count":0,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/18678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media\/18672"}],"wp:attachment":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media?parent=18678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/categories?post=18678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/tags?post=18678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}