{"id":22292,"date":"2026-03-31T13:37:04","date_gmt":"2026-03-31T13:37:04","guid":{"rendered":"https:\/\/nnpc-marine.com\/member-circular-big-oil-spill-affecting-ports-of-mexico-veracruz-and-coatzacoalcos\/"},"modified":"2026-04-02T11:35:46","modified_gmt":"2026-04-02T11:35:46","slug":"grosse-oelverschmutzung-in-mexikanischen-haefen-veracruz-und-coatzacoalcos","status":"publish","type":"post","link":"https:\/\/nnpc-marine.com\/de\/grosse-oelverschmutzung-in-mexikanischen-haefen-veracruz-und-coatzacoalcos\/","title":{"rendered":"Gro\u00dfe \u00d6lverschmutzung in mexikanischen H\u00e4fen (Veracruz und Coatzacoalcos)"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_8c9a1c3b\"><div class=\"wpb_wrapper\"><p>Wir wurden von unserem mexikanischen Korrespondenten, P&amp;I Services Mexico, \u00fcber eine anhaltende \u00d6lverschmutzung im Golf von Mexiko informiert, die derzeit den Betrieb in den H\u00e4fen von Veracruz und, in geringerem Ma\u00dfe, Coatzacoalcos beeintr\u00e4chtigt.<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"w-image us_custom_7cd9500e align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1200\" height=\"670\" src=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2026\/03\/big_oil_spill_affecting_ports_of_mexico-.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2026\/03\/big_oil_spill_affecting_ports_of_mexico-.jpg 1200w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2026\/03\/big_oil_spill_affecting_ports_of_mexico--300x168.jpg 300w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2026\/03\/big_oil_spill_affecting_ports_of_mexico--1024x572.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><\/div><div class=\"w-separator size_custom\" style=\"height:50px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Seit Anfang M\u00e4rz 2026 hat sich die \u00d6lverschmutzung \u00fcber etwa 600 Kilometer K\u00fcstenlinie ausgebreitet. Obwohl die Ermittlungen der mexikanischen Beh\u00f6rden noch andauern, wird vermutet, dass der Vorfall mit einer m\u00f6glichen Einleitung durch ein unbekanntes Schiff in Zusammenhang steht. Erhebliche Mengen an Roh\u00f6l haben inzwischen die Hafengebiete erreicht und es sind weiterhin \u00d6lflecken vorhanden.<\/p>\n<p>Schiffe, die die betroffenen H\u00e4fen anlaufen, m\u00fcssen verschiedene betriebliche Risiken einkalkulieren. \u00d6llachen auf dem Wasser k\u00f6nnen Schiffe verunreinigen und Anlagen und Beschichtungen angreifen. Wenn ein verunreinigtes Schiff in einen Hafen einl\u00e4uft, kann dies zu Inspektionen und gegebenenfalls zu Geldstrafen oder zur Festsetzung f\u00fchren. Dar\u00fcber hinaus k\u00f6nnen Reinigungs- und Inspektionsauflagen zu betrieblichen Verz\u00f6gerungen f\u00fchren.<\/p>\n<p>Mitgliedern, die in diesem Gebiet unterwegs sind, wird dringend empfohlen, beim Anlaufen der betroffenen Gew\u00e4sser besonders wachsam zu sein und vorbeugende Ma\u00dfnahmen zu ergreifen, wie beispielsweise den Einsatz von \u00d6lsperren beim Anlegen. Im Falle einer Verschmutzung des Schiffsrumpfs sind unverz\u00fcglich Ma\u00dfnahmen zu ergreifen, um in Zusammenarbeit mit den lokalen Korrespondenten die Inspektion, Reinigung und ordnungsgem\u00e4\u00dfe Dokumentation zu veranlassen.<\/p>\n<p>Mitglieder, die Unterst\u00fctzung ben\u00f6tigen, werden gebeten, sich an das Schadenteam des NNPC zu wenden, das rund um die Uhr erreichbar ist: <a href=\"mailto:claims@nnpc-marine.com\">claims@nnpc-marine.com<\/a>.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Wir wurden von unserem mexikanischen Korrespondenten, P&amp;I Services Mexico, \u00fcber eine anhaltende \u00d6lverschmutzung im Golf von Mexiko informiert, die derzeit den Betrieb in den H\u00e4fen von Veracruz und, in geringerem Ma\u00dfe, Coatzacoalcos beeintr\u00e4chtigt. Seit Anfang M\u00e4rz 2026 hat sich die \u00d6lverschmutzung \u00fcber etwa 600 Kilometer K\u00fcstenlinie ausgebreitet. Obwohl die Ermittlungen der mexikanischen Beh\u00f6rden noch andauern,...","protected":false},"author":5,"featured_media":22293,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[12],"tags":[124,200],"class_list":["post-22292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachricht","tag-haefen","tag-mexico"],"_links":{"self":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/22292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/comments?post=22292"}],"version-history":[{"count":0,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/22292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media\/22293"}],"wp:attachment":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media?parent=22292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/categories?post=22292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/tags?post=22292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}