{"id":9259,"date":"2021-06-29T09:35:52","date_gmt":"2021-06-29T09:35:52","guid":{"rendered":"https:\/\/nlnnpc-mashinaki.savviihq.com\/nnpc-loss-prevention-carriage-of-cargo\/"},"modified":"2025-06-28T21:00:40","modified_gmt":"2025-06-28T21:00:40","slug":"nnpc-schadenpraevention-beim-frachttransport","status":"publish","type":"post","link":"https:\/\/nnpc-marine.com\/de\/nnpc-schadenpraevention-beim-frachttransport\/","title":{"rendered":"NNPC schadenpraevention beim frachttransport"},"content":{"rendered":"<section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1200\" height=\"275\" src=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2021\/11\/publicatie-header-carriageofcargo.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/nnpc-marine.com\/wp-content\/uploads\/2021\/11\/publicatie-header-carriageofcargo.jpg 1200w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2021\/11\/publicatie-header-carriageofcargo-300x69.jpg 300w, https:\/\/nnpc-marine.com\/wp-content\/uploads\/2021\/11\/publicatie-header-carriageofcargo-1024x235.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Frachtschaden kann passieren &#8211; aber die Risiken sind beherrschbar<\/h2>\n<p>Der Noord Nederlandsche P&amp;I Club (NNPC) unterst\u00fctzt seine Mitglieder bereits seit knapp 80 Jahren mit Dienstleistungen zur Schadenpr\u00e4vention. Die Verh\u00fctung von Schaden spielt beim Risikomanagement eine wichtige Rolle und dient in Anbetracht des Prinzips der Gegenseitigkeit den Interessen aller NNPC-Mitglieder.<\/p>\n<p>Der Kapit\u00e4n und die Besatzung haben bei der Schadenverh\u00fctung eine entscheidende Funktion. Dieser Artikel konzentriert sich auf Ladungssch\u00e4den und soll eine allgemeine Anleitung f\u00fcr die Schadenverh\u00fctung an Bord geben, die dem Kapit\u00e4n und der Besatzung in den verschiedenen Phasen der Schifffahrt helfen kann, Sch\u00e4den an der Ladung zu vermeiden oder zu minimieren.<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>Vor dem Verladen<\/h3>\n<p>Bevor mit dem Laden begonnen werden kann, m\u00fcssen mehrere Schritte durchgef\u00fchrt werden:<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>Allgemeines<\/h3>\n<ul>\n<li>\u00dcberpr\u00fcfen Sie die Reiseanweisungen und stellen Sie sicher, dass die Besatzungsmitglieder wissen, was von ihnen erwartet wird.<\/li>\n<li>Best\u00e4tigen Sie, wer f\u00fcr das Beladen, Laschen und Sichern verantwortlich ist.<\/li>\n<li>Achten Sie besonders auf die Frachtbestimmungen f\u00fcr Schwergut, IMO-G\u00fcter oder andere risikoreiche Fracht.<\/li>\n<li>Pr\u00fcfen Sie, was bez\u00fcglich der Vermerke auf dem Konnossement vereinbart wurde. Denken Sie daran, dass das Konnossement der Beweis f\u00fcr den Zustand der Ladung ist, wie sie an Bord des Schiffes genommen wurde. Wenn Bemerkungen notwendig erscheinen, aber nicht zul\u00e4ssig sind, muss die betreffende Ladung abgelehnt werden.<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>Vorbereitung des Schiffes<\/h3>\n<ul>\n<li>Sind die Lader\u00e4ume ordnungsgem\u00e4\u00df vorbereitet und inspiziert?<\/li>\n<li>Sind die Bilge, die R\u00fcckschlagventile und die Lukendichtungen in gutem Zustand und frei von R\u00fcckst\u00e4nden fr\u00fcherer Ladungen?<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>Sammeln und Speichern von Informationen<\/h3>\n<ul>\n<li>Legen Sie auf Ihrem Computer einen Ordner an, in dem Sie die Informationen \u00fcber die Reise an einem Ort speichern.<\/li>\n<li>F\u00fchren Sie die erste Tiefgangsmessung* durch, bevor die Fracht geladen wird.<\/li>\n<li>Wenn m\u00f6glich, fotografieren und dokumentieren Sie die Lagerbedingungen der Ladung.<\/li>\n<li>Wurden alle relevanten Ladedokumente (z. B. eine vollst\u00e4ndige IMSBC-Versendererkl\u00e4rung) und Spezifikationen vorgelegt? Stimmen diese Spezifikationen mit der tats\u00e4chlichen Ladung \u00fcberein?<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>Allgemeine bew\u00e4hrte Praktiken<\/h3>\n<ul>\n<li>Sorgen Sie in jedem Fall f\u00fcr ein sicheres Arbeitsumfeld. Halten Sie sich das bei der Beaufsichtigung der Arbeiten immer vor Augen.<\/li>\n<li>Stellen Sie sicher, dass die ISM- und ISPS-Vorschriften eingehalten werden, insbesondere in Bezug auf Sicherheit, Wachdienst und Verhinderung blinder Passagiere.<\/li>\n<li>Unterschreiben oder stempeln Sie keine Dokumente, die die Rechte des Reeders gef\u00e4hrden k\u00f6nnten. Wenn Sie Dokumente unterschreiben m\u00fcssen, insbesondere solche in einer Fremdsprache, f\u00fcgen Sie unter Ihrer Unterschrift den Vermerk \u201efor receipt only and without prejudice\u201c (nur f\u00fcr Empfang und ohne Einschr\u00e4nkung der Rechte) hinzu.<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>Bew\u00e4hrte Praktiken beim Verladen<\/h3>\n<p>Wir empfehlen, dass der Kapit\u00e4n und\/oder die Besatzung die Vorg\u00e4nge w\u00e4hrend des Ladens st\u00e4ndig \u00fcberwachen. Insbesondere raten wir dazu, dass der Kapit\u00e4n und\/oder die Besatzung:<\/p>\n<ul>\n<li>Lade-, Stau- und Laschvorg\u00e4nge fotografiert und dokumentiert;<\/li>\n<li>den Zustand der Ladung ordnungsgem\u00e4\u00df dokumentiert, beispielsweise durch Ausf\u00fcllen des Vorladeprotokolls des Kapit\u00e4ns*;<\/li>\n<li>unmittelbar nach dem Beladen eine abschlie\u00dfende Tiefgangsmessung* durchf\u00fchrt. Das auf dem Frachtbrief angegebene Gewicht muss mit den Berechnungen \u00fcbereinstimmen;<\/li>\n<li>keine \u201eFreight Prepaid\u201c-Konnossemente ausstellt, es sei denn, die Reeder haben dies ausdr\u00fccklich angewiesen.<\/li>\n<\/ul>\n<p>Dar\u00fcber hinaus wird empfohlen:<\/p>\n<ul>\n<li>die Lader\u00e4ume unmittelbar nach dem Laden in Anwesenheit von Vertretern der Ladungsempf\u00e4nger und des Befrachters* zu verplomben;<\/li>\n<li>bei Schwergut oder Projektladung daf\u00fcr zu sorgen, dass die Ladung entsprechend dem Laschplan und den Stabilit\u00e4tsberechnungen gelascht wird.<\/li>\n<\/ul>\n<p>Der Kapit\u00e4n ist, auch unter FIOS-Bedingungen, letztlich f\u00fcr die Seet\u00fcchtigkeit seines Schiffes verantwortlich. Sollten zu irgendeinem Zeitpunkt Zweifel an der Beladung, Laschung oder Stauung bestehen, wenden Sie sich bitte an die Gesch\u00e4ftsstelle oder NNPC, um Rat zu erhalten.<\/p>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>W\u00e4hrend der Reise<\/h3>\n<p>W\u00e4hrend der Reise muss die Besatzung:<\/p>\n<ul>\n<li>die Ladung, Stauung und Laschung regelm\u00e4\u00dfig kontrollieren. Melden Sie Ladungsverschiebungen, Eindringen von Seewasser, Schwitzen der Ladung oder andere Probleme so schnell wie m\u00f6glich und stellen Sie sicher, dass die Kontrollen und Feststellungen in den Logb\u00fcchern des Schiffes festgehalten werden.<\/li>\n<li>Setzen Sie sich mit der Gesch\u00e4ftsstelle in Verbindung, wenn der Verdacht besteht, dass die Ladung besch\u00e4digt wurde oder sich verschoben hat, beziehungsweise wenn dies tats\u00e4chlich der Fall ist. Fotografieren Sie die Situation &#8211; sofern dies gefahrlos m\u00f6glich ist &#8211; und beobachten Sie die Entwicklung.<\/li>\n<li>Wenn Sie angewiesen wurden, zu r\u00e4uchern oder zu l\u00fcften, stellen Sie sicher, dass die Bedingungen daf\u00fcr geeignet sind. Setzen Sie sich unverz\u00fcglich mit der Gesch\u00e4ftsstelle in Verbindung, wenn die Temperatur der Ladung unerwartet ansteigt oder sichtbarer Rauch entsteht.<\/li>\n<\/ul>\n<\/div><\/div><div class=\"w-separator size_custom\" style=\"height:30px\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h3>Im L\u00f6schhafen<\/h3>\n<p>Da die meisten Probleme mit der Ladung in der Regel w\u00e4hrend oder nach dem Entladen gemeldet werden, ist es wichtig, dass die Besatzung die Entladevorg\u00e4nge und eventuell auftretende Probleme ordnungsgem\u00e4\u00df dokumentiert, indem sie sich an die folgenden Empfehlungen h\u00e4lt:<\/p>\n<ul>\n<li>F\u00fchren Sie die erste Tiefgangsmessung* vor Beginn des L\u00f6schens und die letzte Tiefgangsmessung* nach dem L\u00f6schen durch und notieren Sie das Gewicht der gel\u00f6schten Ladung.<\/li>\n<li>Entfernen Sie die Verplombung gem\u00e4\u00df dem Entplombungsprotokoll. Filmen oder fotografieren Sie immer das Aufbrechen der Verplombung.<\/li>\n<li>Besprechen Sie die Entladevorg\u00e4nge und Arbeitsverfahren im Voraus mit den Stauern.<\/li>\n<li>Wenn die Ladung in Lastwagen entladen wird, sollten Sie verfolgen, wie viele Lastwagen beladen wurden.<\/li>\n<li>Sofern nicht anders angewiesen, sollte die Ladung nicht ohne Vorlage der Originalkonnossemente entladen werden.<\/li>\n<li>Fotografieren und dokumentieren Sie die L\u00f6scharbeiten. Achten Sie besonders auf Unregelm\u00e4\u00dfigkeiten, wie auslaufende Fl\u00fcssigkeiten oder Diebstahl.<\/li>\n<li>Achten Sie darauf, wer an Bord gelassen wird. F\u00fchren Sie eine Besucherliste, in der der vollst\u00e4ndige Name und die Eigenschaft aller Besucher eingetragen werden. Verlangen Sie immer einen Identit\u00e4tsnachweis und bewahren Sie, wenn es sich um Sachverst\u00e4ndige, Rechtsanw\u00e4lte oder Korrespondenten handelt, eine Kopie ihrer Visitenkarte auf.<\/li>\n<\/ul>\n<p><em>* Der NNPC hat Muster der in diesem Artikel genannten Protokolle \u00fcber das Vorladen, die Verplombung und die Entplombung sowie die Messung des Tiefgangs erstellt, die auf unserer Website verf\u00fcgbar sind.<\/em><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Frachtschaden kann passieren &#8211; aber die Risiken sind beherrschbar Der Noord Nederlandsche P&amp;I Club (NNPC) unterst\u00fctzt seine Mitglieder bereits seit knapp 80 Jahren mit Dienstleistungen zur Schadenpr\u00e4vention. Die Verh\u00fctung von Schaden spielt beim Risikomanagement eine wichtige Rolle und dient in Anbetracht des Prinzips der Gegenseitigkeit den Interessen aller NNPC-Mitglieder. Der Kapit\u00e4n und die Besatzung haben...","protected":false},"author":4,"featured_media":16741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[11],"tags":[],"class_list":["post-9259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publication-de"],"_links":{"self":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/9259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/comments?post=9259"}],"version-history":[{"count":0,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/posts\/9259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media\/16741"}],"wp:attachment":[{"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/media?parent=9259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/categories?post=9259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nnpc-marine.com\/de\/wp-json\/wp\/v2\/tags?post=9259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}