{"id":13567,"date":"2024-07-18T08:15:23","date_gmt":"2024-07-18T08:15:23","guid":{"rendered":"https:\/\/nnpc.tempurl.host\/?p=13567"},"modified":"2025-06-29T12:46:46","modified_gmt":"2025-06-29T12:46:46","slug":"nnpc-masterclass-betreft-eu-ets","status":"publish","type":"post","link":"https:\/\/nnpc-marine.com\/nl\/nnpc-masterclass-betreft-eu-ets\/","title":{"rendered":"NNPC Masterclass betreft EU ETS"},"content":{"rendered":"<p><strong>De eerste NNPC Masterclass vond plaats op 16 juli 2024 in de Rietschans in Haren. In samenwerking met Reed Smith werd de sessie gepresenteerd en bood inzichten van hun scheepvaart- en energieteams over de toepassing van het EU Emissions Trading Scheme (EU ETS) op de scheepvaartsector, evenals de implicaties voor NNPC-leden onder hun charterparty-overeenkomsten. Er werd speciale nadruk gelegd op mandaatclausules in beheersovereenkomsten en ETS-clausules voor tijdbevrachting.<\/strong><\/p>\n<p>Het evenement was goed bezocht en leidde tot levendige discussies over de EU ETS, brandstofeffici\u00ebntie en de bredere impact van EU- en mondiale emissiebeleidsmaatregelen. We danken alle leden en aanwezigen voor hun deelname, met speciale dank aan Jeb Clulow en Julie Vaughan van Reed Smith voor hun uitstekende presentaties.<\/p>\n<p>We moedigen onze leden aan om contact op te nemen met eventuele vragen over de EU ETS en kijken ernaar uit u te verwelkomen bij onze tweede Masterclass, die zich zal richten op sancties. De datum wordt binnenkort bevestigd.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De eerste NNPC Masterclass vond plaats op 16 juli 2024 in de Rietschans in Haren. In samenwerking met Reed Smith werd de sessie gepresenteerd en bood inzichten van hun scheepvaart- en energieteams over de toepassing van het EU Emissions Trading Scheme (EU ETS) op de scheepvaartsector, evenals de implicaties voor NNPC-leden onder hun charterparty-overeenkomsten. Er&#8230;<\/p>\n","protected":false},"author":4,"featured_media":13564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[5],"tags":[74],"class_list":["post-13567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nieuws","tag-nnpc-nl"],"_links":{"self":[{"href":"https:\/\/nnpc-marine.com\/nl\/wp-json\/wp\/v2\/posts\/13567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nnpc-marine.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nnpc-marine.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/nl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/nl\/wp-json\/wp\/v2\/comments?post=13567"}],"version-history":[{"count":0,"href":"https:\/\/nnpc-marine.com\/nl\/wp-json\/wp\/v2\/posts\/13567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nnpc-marine.com\/nl\/wp-json\/wp\/v2\/media\/13564"}],"wp:attachment":[{"href":"https:\/\/nnpc-marine.com\/nl\/wp-json\/wp\/v2\/media?parent=13567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nnpc-marine.com\/nl\/wp-json\/wp\/v2\/categories?post=13567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nnpc-marine.com\/nl\/wp-json\/wp\/v2\/tags?post=13567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}